{"id":1028,"date":"2024-12-25T16:48:52","date_gmt":"2024-12-25T16:48:52","guid":{"rendered":"https:\/\/nygaardcapital.pro\/about-company"},"modified":"2025-01-17T15:11:42","modified_gmt":"2025-01-17T15:11:42","slug":"about-company","status":"publish","type":"page","link":"https:\/\/nygaardcapital.pro\/fr\/about-company","title":{"rendered":"\u00c0 propos de notre entreprise"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1028\" class=\"elementor elementor-1028\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-d52b2cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d52b2cc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48fa10e\" data-id=\"48fa10e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e7a780 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9e7a780\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Lib\u00e9ration du potentiel des commer\u00e7ants dans le monde entier <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71a8cb4 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"71a8cb4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:750}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tRejoignez une communaut\u00e9 mondiale de traders qui atteignent leurs objectifs financiers gr\u00e2ce \u00e0 des outils avanc\u00e9s, des actifs diversifi\u00e9s et la plateforme de confiance de Nygaard Capital. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a4ff0c elementor-widget elementor-widget-spacer\" data-id=\"8a4ff0c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-53a7aa6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53a7aa6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bc399a7\" data-id=\"bc399a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47c7415 elementor-invisible elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"47c7415\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-47c7415&quot;,&quot;countStart&quot;:1,&quot;countNumber&quot;:5,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:5,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot;+&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-47c7415\" >\n\t\t\t\t\t5\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tAns d'exp\u00e9rience \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d1d90c5\" data-id=\"d1d90c5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5a5046 elementor-invisible elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"a5a5046\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-a5a5046&quot;,&quot;countStart&quot;:1,&quot;countNumber&quot;:24,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:5,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot;\\\/5&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-a5a5046\" >\n\t\t\t\t\t24\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tSupport client \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cd08337\" data-id=\"cd08337\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b349a0 elementor-invisible elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"6b349a0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-6b349a0&quot;,&quot;countStart&quot;:1,&quot;countNumber&quot;:200,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:5,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot;K+&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-6b349a0\" >\n\t\t\t\t\t200\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tComptes ouverts \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-03786d4\" data-id=\"03786d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f969a4 elementor-invisible elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"4f969a4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-4f969a4&quot;,&quot;countStart&quot;:1,&quot;countNumber&quot;:400,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:5,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot;+&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-4f969a4\" >\n\t\t\t\t\t400\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tOutils \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-9aeab64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9aeab64\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fcd864c elementor-invisible\" data-id=\"fcd864c\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:250}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93cc04d elementor-widget elementor-widget-spacer\" data-id=\"93cc04d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a289fad elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a289fad\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rotateInUpLeft&quot;,&quot;_animation_delay&quot;:700}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c0 propos de Nygaard Capital <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f92a18e elementor-section-height-min-height elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-invisible\" data-id=\"f92a18e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9539479 animated-fast elementor-invisible\" data-id=\"9539479\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69ef3c0 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"69ef3c0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"894\" src=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/Who-We-Are.png\" class=\"attachment-full size-full wp-image-399\" alt=\"\" srcset=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/Who-We-Are.png 720w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/Who-We-Are-242x300.png 242w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/Who-We-Are-523x650.png 523w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b139069\" data-id=\"b139069\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22a855f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"22a855f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rotateInUpLeft&quot;,&quot;_animation_delay&quot;:550}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qui sommes-nous <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-541ebb8 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"541ebb8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rotateInUpLeft&quot;,&quot;_animation_delay&quot;:700}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNygaard Capital is a trusted trading partner with a mission to empower traders by providing innovative tools, a secure environment, and unmatched market opportunities. Whether you\u2019re new to trading or a seasoned professional, our platform is designed to help you succeed.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fefefe9 elementor-section-height-min-height elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-invisible\" data-id=\"fefefe9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4429e4b animated-fast elementor-invisible\" data-id=\"4429e4b\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2609e73 elementor-widget elementor-widget-image\" data-id=\"2609e73\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"894\" src=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/What-We-Offer.png\" class=\"attachment-full size-full wp-image-398\" alt=\"\" srcset=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/What-We-Offer.png 720w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/What-We-Offer-242x300.png 242w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/What-We-Offer-523x650.png 523w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fd2b733\" data-id=\"fd2b733\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef5adc6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ef5adc6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rotateInUpLeft&quot;,&quot;_animation_delay&quot;:550}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Que proposons-nous <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7380ccc elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7380ccc\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rotateInUpLeft&quot;,&quot;_animation_delay&quot;:700}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tChez Nygaard Capital, nous combinons une plateforme moderne, des conditions de trading comp\u00e9titives et une \u00e9quipe de support d\u00e9di\u00e9e pour rendre votre interaction avec le march\u00e9 confortable et rentable. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac7d79d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac7d79d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-539c4ca\" data-id=\"539c4ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cd34c8 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6cd34c8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi nous choisir <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cc9bb1 elementor-widget elementor-widget-spacer\" data-id=\"9cc9bb1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0842fdf elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"0842fdf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:750}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tD\u00e9couvrez les principaux avantages qui font de Nygaard Capital le choix pr\u00e9f\u00e9r\u00e9 des traders du monde entier\u00a0: des plateformes de pointe, des actifs diversifi\u00e9s, une s\u00e9curit\u00e9 de premier ordre et une assistance in\u00e9gal\u00e9e. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-291f265 elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-button\" data-id=\"291f265\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;1000&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/register\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Rejoignez Nygaard Capital d\u00e8s aujourd'hui <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4160f5c\" data-id=\"4160f5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e640b61 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"e640b61\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:850}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/Advanced-Trading-Platform.svg\" class=\"attachment-full size-full\" alt=\"Plateforme de trading avanc\u00e9e \" srcset=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Advanced-Trading-Platform.svg 150w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Advanced-Trading-Platform.svg 300w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Advanced-Trading-Platform.svg 1024w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Advanced-Trading-Platform.svg 90w\" sizes=\"(max-width: 90px) 100vw, 90px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tPlateforme de trading avanc\u00e9e \t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\tTradez sur MT5 en ayant acc\u00e8s \u00e0 des outils de pointe, \u00e0 une ex\u00e9cution instantan\u00e9e et \u00e0 une interface conviviale. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecf3b49 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"ecf3b49\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/Unmatched-Security.svg\" class=\"attachment-full size-full\" alt=\"S\u00e9curit\u00e9 in\u00e9gal\u00e9e \" srcset=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Unmatched-Security.svg 150w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Unmatched-Security.svg 300w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Unmatched-Security.svg 1024w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Unmatched-Security.svg 90w\" sizes=\"(max-width: 90px) 100vw, 90px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tS\u00e9curit\u00e9 in\u00e9gal\u00e9e \t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\tVos fonds et vos donn\u00e9es sont prot\u00e9g\u00e9s par des protocoles de s\u00e9curit\u00e9 avanc\u00e9s. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2829c4b bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"2829c4b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/Education-and-Support.svg\" class=\"attachment-full size-full\" alt=\"Formation et assistance \" srcset=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Education-and-Support.svg 150w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Education-and-Support.svg 300w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Education-and-Support.svg 1024w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Education-and-Support.svg 90w\" sizes=\"(max-width: 90px) 100vw, 90px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tFormation et assistance \t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\tB\u00e9n\u00e9ficiez d&rsquo;avis d&rsquo;experts, d&rsquo;analyses de march\u00e9 et d&rsquo;une assistance 24 heures sur 24, 7 jours sur 7, pour maximiser votre r\u00e9ussite commerciale. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2efa544\" data-id=\"2efa544\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c690080 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"c690080\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:750}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/Diverse-Asset-Selection.svg\" class=\"attachment-full size-full\" alt=\"Diversit\u00e9 des actifs \" srcset=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Diverse-Asset-Selection.svg 150w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Diverse-Asset-Selection.svg 300w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Diverse-Asset-Selection.svg 1024w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Diverse-Asset-Selection.svg 90w\" sizes=\"(max-width: 90px) 100vw, 90px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tDiversit\u00e9 des actifs \t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\tExplorez les opportunit\u00e9s sur le march\u00e9 Forex, des actions, des indices et des mati\u00e8res premi\u00e8res \u2014 le tout en un seul endroit. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4a5e27 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"d4a5e27\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:1050}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/Transparent-Pricing.svg\" class=\"attachment-full size-full\" alt=\"Prix transparents \" srcset=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Transparent-Pricing.svg 150w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Transparent-Pricing.svg 300w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Transparent-Pricing.svg 1024w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Transparent-Pricing.svg 90w\" sizes=\"(max-width: 90px) 100vw, 90px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tPrix transparents \t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\tChoisissez des comptes avec des \u00e9carts comp\u00e9titifs, des commissions faibles et pas de frais cach\u00e9s. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-203ca5f bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"203ca5f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:1050}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/2025\/01\/Fast-and-Flexible-Withdrawals.svg\" class=\"attachment-full size-full\" alt=\"Retraits rapides et flexibles \" srcset=\"https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Fast-and-Flexible-Withdrawals.svg 150w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Fast-and-Flexible-Withdrawals.svg 300w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Fast-and-Flexible-Withdrawals.svg 1024w, https:\/\/nygaardcapital.pro\/wp-content\/uploads\/\/2025\/01\/Fast-and-Flexible-Withdrawals.svg 90w\" sizes=\"(max-width: 90px) 100vw, 90px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tRetraits rapides et flexibles \t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\tProfitez d&rsquo;un acc\u00e8s rapide et pratique \u00e0 vos fonds gr\u00e2ce aux nombreuses m\u00e9thodes de paiement disponibles. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Lib\u00e9ration du potentiel des commer\u00e7ants dans le monde entier Rejoignez une communaut\u00e9 mondiale de traders qui atteignent leurs objectifs financiers gr\u00e2ce \u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1028","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nygaardcapital.pro\/fr\/wp-json\/wp\/v2\/pages\/1028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nygaardcapital.pro\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nygaardcapital.pro\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nygaardcapital.pro\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nygaardcapital.pro\/fr\/wp-json\/wp\/v2\/comments?post=1028"}],"version-history":[{"count":4,"href":"https:\/\/nygaardcapital.pro\/fr\/wp-json\/wp\/v2\/pages\/1028\/revisions"}],"predecessor-version":[{"id":1107,"href":"https:\/\/nygaardcapital.pro\/fr\/wp-json\/wp\/v2\/pages\/1028\/revisions\/1107"}],"wp:attachment":[{"href":"https:\/\/nygaardcapital.pro\/fr\/wp-json\/wp\/v2\/media?parent=1028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}